{"id":5710,"date":"2019-09-01T11:47:14","date_gmt":"2019-09-01T09:47:14","guid":{"rendered":"https:\/\/www.pixolum.com\/blog\/?p=5710"},"modified":"2021-08-16T11:33:29","modified_gmt":"2021-08-16T09:33:29","slug":"pferdefotografie","status":"publish","type":"post","link":"https:\/\/www.pixolum.com\/blog\/fotografie\/pferdefotografie","title":{"rendered":"Pferdefotografie &#8211; Der komplette Ratgeber"},"content":{"rendered":"<p><strong>Die Pferdefotografie ist eine absolute\u00a0Leidenschaftsdisziplin &#8211; aus gutem Grund! Pferde sind eines der elegantesten, anmutigsten und majest\u00e4tischsten Motive, die du als Fotograf*in vor die Kamera bekommen kannst. Um diesen wunderbaren Tieren gerecht zu werden und mit deinen Bildern am Ende wirklich zufrieden zu sein, solltest du einige Faktoren ber\u00fccksichtigen. Doch keine Sorge! In diesem Artikel verrate ich dir\u00a0alles, was du \u00fcber\u00a0die Pferdefotografie wissen musst und mit welchen Geheimtipps du zum Pferdefl\u00fcsterer wirst!<\/strong><\/p>\n<figure id=\"attachment_6035\" aria-describedby=\"caption-attachment-6035\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6035 size-large\" src=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/Pferdefotografie-Ratgeber-Tipps-800x533.jpg\" alt=\"Pferdefotografie Ratgeber und Tipps\" width=\"800\" height=\"533\" title=\"\" srcset=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/Pferdefotografie-Ratgeber-Tipps-800x533.jpg 800w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/Pferdefotografie-Ratgeber-Tipps-250x167.jpg 250w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/Pferdefotografie-Ratgeber-Tipps-120x80.jpg 120w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/Pferdefotografie-Ratgeber-Tipps.jpg 1200w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-6035\" class=\"wp-caption-text\">Pferdefotografie Ratgeber und Tipps (@fabuchao)<\/figcaption><\/figure>\n<h2>Ausr\u00fcstung<\/h2>\n<p>Als angehende*r Fotograf*in ist dir wahrscheinlich l\u00e4ngst bewusst, dass eine\u00a0<strong>gute Vorbereitung\u00a0<\/strong>die beste Garantie f\u00fcr ein tolles Ergebnis ist. Zur Vorbereitung geh\u00f6rt nat\u00fcrlich &#8211; neben dem\u00a0<strong>Motiv\u00a0<\/strong>und der\u00a0<strong>Location\u00a0<\/strong>&#8211; in erster Linie auch deine <a href=\"https:\/\/www.pixolum.com\/blog\/fotografie\/unsere-foto-ausruestung\">Fotoausr\u00fcstung<\/a>. Bei der\u00a0<strong>Pferdefotografie\u00a0<\/strong>rate ich dir, folgende Faktoren im Kopf zu behalten:<\/p>\n<ul class=\"iconlist\">\n<li>Das Pferd ist ein relativ gro\u00dfes Motiv; deshalb musst du ein spezielles Augenmerk auf die Proportionen legen. Vermeide Objektive, die eine Verzerrung erzeugen (z.B. <a href=\"https:\/\/www.pixolum.com\/blog\/fotografie\/weitwinkelobjektiv\">Weitwinkelobjektive<\/a>) und achte auf die Positionierung deines Motivs.<\/li>\n<li>Du arbeitest hier eng mit einem empfindsamen Lebewesen zusammen. Neben einigen allgemeinen Richtlinien f\u00fcr beidseitige Sicherheit und Entspanntheit (dazu sp\u00e4ter mehr) solltest du das auch bei der Wahl deiner Ausr\u00fcstung beachten. Pferde k\u00f6nnen beispielsweise schreckhaft auf Ausl\u00f6serger\u00e4usche oder zu gro\u00dfe N\u00e4he reagieren.<\/li>\n<li>Bei der Aufnahmesession im Lebensraum eines Pferdes kann es auch mal staubig oder dreckig zugehen. Achte deshalb auf ausreichenden <a href=\"https:\/\/www.pixolum.com\/blog\/fotografie\/fotoausruestung-schuetzen\">Schutz<\/a> deiner wertvollen Ausr\u00fcstung.<\/li>\n<\/ul>\n<h3>Meine Objektiv-Tipps f\u00fcr die Pferdefotografie<\/h3>\n<h4><span class=\"headingSquareNumber\">#1<\/span>\u00a0Standardobjektiv \/ Festbrennweite<\/h4>\n<div class=\"pixol-adsense-mitte-beginn-artiel\" style=\"float: right;\" id=\"pixol-1031846028\"><script async type=\"text\/javascript\" src=\"\/\/cdn.carbonads.com\/carbon.js?serve=CE7IL2JM&placement=wwwpixolumcom\" id=\"_carbonads_js\"><\/script><\/div><p>Wie bereits erw\u00e4hnt sind einige Objektivtypen f\u00fcr die\u00a0<strong>Pferdefotografie\u00a0<\/strong>nicht unbedingt geeignet, was vor allem an der Verzerrung liegt. Ein zuverl\u00e4ssig zufriedenstellendes Bildergebnis erh\u00e4ltst du mit einem\u00a0<strong>Standardobjektiv<\/strong>. Darunter versteht man ein Objektiv, dessen erzeugtes Bild in etwa der Wahrnehmung des menschlichen Auges entspricht. Standardobjektive decken einen Blickwinkel von ca. 50 bis 55 Grad ab und sind wegen ihrer weit zu \u00f6ffnenden Blende auch f\u00fcr Aufnahmen bei <a href=\"https:\/\/www.pixolum.com\/blog\/fotografie\/available-light\">schwachem Umgebungslicht<\/a> super geeignet. Die offene Blende erm\u00f6glicht zudem den wundersch\u00f6nen\u00a0<a href=\"https:\/\/www.pixolum.com\/blog\/fotografie\/bokeh-effekt-tutorial-die-schoenheit-der-unschaerfe\">Bokeh-Effekt<\/a>.<\/p>\n<blockquote><p>Ganz konkret empfehle ich dir f\u00fcr die\u00a0<strong>Pferdefotografie\u00a0<\/strong>ein\u00a0<strong>Standardobjektiv mit einer festen Brennweite von 50 mm<\/strong>.<\/p><\/blockquote>\n<p>Du m\u00f6chtest dein Wissen \u00fcber die Brennweite vertiefen? Dann lies doch <a href=\"https:\/\/www.pixolum.com\/blog\/fotografie\/brennweite-und-brennpunkt-verstehen-besser-fotografieren\">hier<\/a> weiter. Oder informiere dich in <a href=\"https:\/\/www.pixolum.com\/blog\/fotografie\/festbrennweite\">diesem Artikel<\/a> \u00fcber Festbrennweiten.<\/p>\n<figure id=\"attachment_5979\" aria-describedby=\"caption-attachment-5979\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5979 size-large\" src=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-50mm-objektiv-800x521.jpg\" alt=\"Pferdefotografie 50mm Objektiv\" width=\"800\" height=\"521\" title=\"\" srcset=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-50mm-objektiv-800x521.jpg 800w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-50mm-objektiv-250x163.jpg 250w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-50mm-objektiv-120x78.jpg 120w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-5979\" class=\"wp-caption-text\">Festbrennweite: Canon 50 mm Objektiv (@davecraige, unsplash)<\/figcaption><\/figure>\n<h4><span class=\"headingSquareNumber\">#2<\/span>\u00a0Teleobjektiv<\/h4>\n<p>Nicht nur mit einem Standardobjektiv kannst du in der<strong> Pferdefotografie\u00a0<\/strong>erfolgreich durchstarten. Auch ein\u00a0<strong>Teleobjektiv\u00a0<\/strong>bietet dir einige Vorteile:<\/p><div class=\"pixol-inhalt_3\" style=\"margin-bottom: 30px;\" id=\"pixol-2699626900\"><h4>Kennst du schon meine 52 weltbesten Spickzettel?<\/h4>\r\n<div class=\"spickteaser\">\r\n<div class=\"row\">\r\n<div class=\"col-sm-7\">\r\n\t<a href=\"https:\/\/www.pixolum.com\/blog\/downloads\/fotografie-spickzettel?utm_source=pixolum&utm_medium=blog_inarticle&utm_campaign=spk_pix_sale_30&utm_term=p79\"><img class=\"alignnone size-full wp-image-8300\" src=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/10\/Fotospickzettel-pixolum-500px.jpg\" alt=\"Fotografie Spickzettel\" loading=\u201dlazy\u201d \/><\/a>\r\n\t<\/div>\r\n<div class=\"col-sm-5\">\r\n<a href=\"https:\/\/www.pixolum.com\/blog\/downloads\/fotografie-spickzettel?utm_source=pixolum&utm_medium=blog_inarticle&utm_campaign=spk_pix_sale_30&utm_term=p79\">\r\n\t<ul class=\"check_icon_list check_icon_list--spickzettel\">\r\n\t\t<li>Mein ganzes Fotowissen<\/li>\r\n\t\t<li>Bessere Fotos in 5 Minuten<\/li>\r\n\t\t<li>Referenz zum Nachschlagen<\/li>\r\n\t\t<li>Kompakt, immer dabei!<\/li>\r\n\t\t<li>Rabatt nicht verpassen!<b><span>-50%<\/span><\/b><\/li>\r\n\t<\/ul>\r\n\t<div class=\"trenner_30\"><\/div>\r\n<\/a>\r\n<a href=\"https:\/\/www.pixolum.com\/blog\/downloads\/fotografie-spickzettel?utm_source=pixolum&utm_medium=blog_inarticle&utm_campaign=spk_pix_sale_30&utm_term=p79\" class=\"btn btn-primary btn-lg btn-block\">Ou ja, zeig mal!<\/a><\/div>\r\n<\/div>\r\n<\/div>\r\n<hr><\/div>\n<ul class=\"proconlist proconlist--positive\">\n<li>Der gr\u00f6\u00dfere Abstand zwischen dir und deinem Motiv kann <strong>f\u00fcr beide Seiten entspannend und befreiend<\/strong> wirken.<\/li>\n<li>Das Teleobjektiv erzeugt eine <strong>nat\u00fcrliche Perspektive<\/strong> ohne Verzerrung und erlaubt dir, auch etwas mehr von der Umgebung mit einzufangen.<\/li>\n<li>Auch beim\u00a0<strong>Pferdesport<\/strong>\u00a0ist ein Teleobjektiv der optimale Begleiter. Damit beh\u00e4ltst du auch bei stark bewegten Motiven den \u00dcberblick.<\/li>\n<\/ul>\n<blockquote><p>Meine Empfehlung: ein\u00a0<strong>Tele-Zoomobjektiv mit einer Brennweite von 70 &#8211; 200 mm<\/strong>.<\/p><\/blockquote>\n<h4><span class=\"headingSquareNumber\">#3<\/span> Weitwinkel- und Fisheye-Objektiv<\/h4>\n<p>Jetzt wirst du dich wahrscheinlich ratlos am Kopf kratzen: Habe ich dir nicht eben erst eingesch\u00e4rft, du sollest Weitwinkelobjektive in der\u00a0<strong>Pferdefotografie\u00a0<\/strong>vermeiden? Ja, habe ich. Sind wir auf der Suche nach einem m\u00f6glichst nat\u00fcrlichen Ergebnis, wirkt sich ein Weitwinkelobjektiv aufgrund der Verzerrung nachteilig aus. Allerdings ist Fotografie ja immer auch Kunst, und in der Kunst gibt es bekanntlich kaum Regeln. Wenn du also Lust hast, ein spannendes, etwas surreales Pferdefoto mit verzerrten Proportionen zu erzeugen, dann schnapp dir ein <strong>Weitwinkel-<\/strong> oder<strong> <a href=\"https:\/\/www.pixolum.com\/blog\/fotografie\/fisheye-objektiv-verzerrungen-fotografieren-mit-dem-fischaugenobjektiv\">Fisheye-Objektiv<\/a> <\/strong>und los gehts!<\/p>\n<div class=\"tippbox\">\n<h5>Pro-Tipp<\/h5>\n<p>Zu Beginn habe ich schon einmal erw\u00e4hnt, dass deine Ausr\u00fcstung bei der Pferdefotografie auch mal ganz sch\u00f6n schmutzig werden kann. Ich empfehle dir deshalb ein\u00a0<strong>Objektivputztuch\u00a0<\/strong>und f\u00fcr die Bildqualit\u00e4t au\u00dferdem einen\u00a0<strong>UV-Filter<\/strong>!<\/p>\n<\/div>\n<h2><span style=\"color: #56585d;font-size: 18px;font-family: Inter, sans-serif;font-weight: 400\">\n<div class=\"aawp\">\n    <div class=\"aawp-grid aawp-grid--col-3\">\n\n            \n        <div class=\"aawp-grid__item\">\n            \n<div class=\"aawp-product aawp-product--vertical\"  data-aawp-product-id=\"B00XKSBMQA\" data-aawp-product-title=\"Canon EF 50mm F1.8 STM Objektiv  58mm Filtergewinde  schwarz\">\n\n    \n    <a class=\"aawp-product__image--link aawp-product__image\" href=\"https:\/\/www.amazon.de\/dp\/B00XKSBMQA?tag=pixolum-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"Canon EF 50mm F1.8 STM Objektiv (58mm Filtergewinde) schwarz\" rel=\"nofollow noopener\" target=\"_blank\" style=\"background-image: url(&#039;https:\/\/m.media-amazon.com\/images\/I\/21escqc-JwL.jpg&#039;);\">\n        <img decoding=\"async\" class=\"aawp-product__image-spacer\" src=\"https:\/\/www.pixolum.com\/blog\/wp-content\/plugins\/aawp\/assets\/img\/thumb-spacer.png\" alt=\"Canon EF 50mm F1.8 STM Objektiv (58mm Filtergewinde) schwarz\" title=\"\"\/>\n    <\/a>\n\n    <div class=\"aawp-product__content\">\n        <a class=\"aawp-product__title\" href=\"https:\/\/www.amazon.de\/dp\/B00XKSBMQA?tag=pixolum-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"Canon EF 50mm F1.8 STM Objektiv (58mm Filtergewinde) schwarz\" rel=\"nofollow noopener\" target=\"_blank\">\n            Canon EF 50mm F1.8 STM Objektiv (58mm...        <\/a>\n\n        <div class=\"aawp-product__meta\">\n            \n                    <\/div>\n    <\/div>\n\n    <div class=\"aawp-product__footer\">\n\n        <div class=\"aawp-product__pricing\">\n\n            \n                    <\/div>\n\n                <a class=\"aawp-button aawp-button--buy aawp-button aawp-button--orange rounded aawp-button--icon aawp-button--icon-amazon-white\" href=\"https:\/\/www.amazon.de\/dp\/B00XKSBMQA?tag=pixolum-21&#038;linkCode=ogi&#038;th=1&#038;psc=1\" title=\"Bei Amazon ansehen\" target=\"_blank\" rel=\"nofollow noopener\">Bei Amazon ansehen<\/a>\n            <\/div>\n<\/div>\n        <\/div>\n\n            \n        <div class=\"aawp-grid__item\">\n            \n<div class=\"aawp-product aawp-product--vertical\"  data-aawp-product-id=\"B07DLGHGW2\" data-aawp-product-title=\"Canon EF 70-200mm F4L IS II USM Objektiv  72mm Filtergewinde  schwarz\">\n\n    \n    <a class=\"aawp-product__image--link aawp-product__image\" href=\"https:\/\/www.amazon.de\/dp\/B07DLGHGW2?tag=pixolum-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"Canon EF 70-200mm F4L IS II USM Objektiv (72mm...\" rel=\"nofollow noopener\" target=\"_blank\" style=\"background-image: url(&#039;https:\/\/m.media-amazon.com\/images\/I\/311UCCg0pwL.jpg&#039;);\">\n        <img decoding=\"async\" class=\"aawp-product__image-spacer\" src=\"https:\/\/www.pixolum.com\/blog\/wp-content\/plugins\/aawp\/assets\/img\/thumb-spacer.png\" alt=\"Canon EF 70-200mm F4L IS II USM Objektiv (72mm...\" title=\"\"\/>\n    <\/a>\n\n    <div class=\"aawp-product__content\">\n        <a class=\"aawp-product__title\" href=\"https:\/\/www.amazon.de\/dp\/B07DLGHGW2?tag=pixolum-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"Canon EF 70-200mm F4L IS II USM Objektiv (72mm...\" rel=\"nofollow noopener\" target=\"_blank\">\n            Canon EF 70-200mm F4L IS II USM Objektiv (72mm...        <\/a>\n\n        <div class=\"aawp-product__meta\">\n            \n                    <\/div>\n    <\/div>\n\n    <div class=\"aawp-product__footer\">\n\n        <div class=\"aawp-product__pricing\">\n\n            \n                    <\/div>\n\n                <a class=\"aawp-button aawp-button--buy aawp-button aawp-button--orange rounded aawp-button--icon aawp-button--icon-amazon-white\" href=\"https:\/\/www.amazon.de\/dp\/B07DLGHGW2?tag=pixolum-21&#038;linkCode=ogi&#038;th=1&#038;psc=1\" title=\"Bei Amazon ansehen\" target=\"_blank\" rel=\"nofollow noopener\">Bei Amazon ansehen<\/a>\n            <\/div>\n<\/div>\n        <\/div>\n\n            \n        <div class=\"aawp-grid__item\">\n            \n<div class=\"aawp-product aawp-product--vertical\"  data-aawp-product-id=\"B002L77LQQ\" data-aawp-product-title=\"Hoya HMC UV  C  Objektiv  67 mm Filter\">\n\n    \n    <a class=\"aawp-product__image--link aawp-product__image\" href=\"https:\/\/www.amazon.de\/dp\/B002L77LQQ?tag=pixolum-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"Hoya HMC UV (C) Objektiv (67 mm Filter)\" rel=\"nofollow noopener\" target=\"_blank\" style=\"background-image: url(&#039;https:\/\/m.media-amazon.com\/images\/I\/31ha0pMGyGL.jpg&#039;);\">\n        <img decoding=\"async\" class=\"aawp-product__image-spacer\" src=\"https:\/\/www.pixolum.com\/blog\/wp-content\/plugins\/aawp\/assets\/img\/thumb-spacer.png\" alt=\"Hoya HMC UV (C) Objektiv (67 mm Filter)\" title=\"\"\/>\n    <\/a>\n\n    <div class=\"aawp-product__content\">\n        <a class=\"aawp-product__title\" href=\"https:\/\/www.amazon.de\/dp\/B002L77LQQ?tag=pixolum-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"Hoya HMC UV (C) Objektiv (67 mm Filter)\" rel=\"nofollow noopener\" target=\"_blank\">\n            Hoya HMC UV (C) Objektiv (67 mm Filter)        <\/a>\n\n        <div class=\"aawp-product__meta\">\n            \n                    <\/div>\n    <\/div>\n\n    <div class=\"aawp-product__footer\">\n\n        <div class=\"aawp-product__pricing\">\n\n            \n                    <\/div>\n\n                <a class=\"aawp-button aawp-button--buy aawp-button aawp-button--orange rounded aawp-button--icon aawp-button--icon-amazon-white\" href=\"https:\/\/www.amazon.de\/dp\/B002L77LQQ?tag=pixolum-21&#038;linkCode=ogi&#038;th=1&#038;psc=1\" title=\"Bei Amazon ansehen\" target=\"_blank\" rel=\"nofollow noopener\">Bei Amazon ansehen<\/a>\n            <\/div>\n<\/div>\n        <\/div>\n\n            \n        <div class=\"aawp-grid__item\">\n            \n<div class=\"aawp-product aawp-product--vertical\"  data-aawp-product-id=\"B01DZGI4I0\" data-aawp-product-title=\"Hama Mikrofaser Reinigungstuch f\u00fcr Kamera Objektiv Filter Brille Display universales Mikrofasertuch im praktischen Neopren Beutel mit Karabiner 15 x 15 cm Mini Pocket Format schwarz\/grau\">\n\n    \n    <a class=\"aawp-product__image--link aawp-product__image\" href=\"https:\/\/www.amazon.de\/dp\/B01DZGI4I0?tag=pixolum-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"Hama Mikrofaser Reinigungstuch f\u00fcr Kamera, Objektiv,...\" rel=\"nofollow noopener\" target=\"_blank\" style=\"background-image: url(&#039;https:\/\/m.media-amazon.com\/images\/I\/31L7BFeUKrL.jpg&#039;);\">\n        <img decoding=\"async\" class=\"aawp-product__image-spacer\" src=\"https:\/\/www.pixolum.com\/blog\/wp-content\/plugins\/aawp\/assets\/img\/thumb-spacer.png\" alt=\"Hama Mikrofaser Reinigungstuch f\u00fcr Kamera, Objektiv,...\" title=\"\"\/>\n    <\/a>\n\n    <div class=\"aawp-product__content\">\n        <a class=\"aawp-product__title\" href=\"https:\/\/www.amazon.de\/dp\/B01DZGI4I0?tag=pixolum-21&amp;linkCode=ogi&amp;th=1&amp;psc=1\" title=\"Hama Mikrofaser Reinigungstuch f\u00fcr Kamera, Objektiv,...\" rel=\"nofollow noopener\" target=\"_blank\">\n            Hama Mikrofaser Reinigungstuch f\u00fcr Kamera,...        <\/a>\n\n        <div class=\"aawp-product__meta\">\n            \n                    <\/div>\n    <\/div>\n\n    <div class=\"aawp-product__footer\">\n\n        <div class=\"aawp-product__pricing\">\n\n            \n                    <\/div>\n\n                <a class=\"aawp-button aawp-button--buy aawp-button aawp-button--orange rounded aawp-button--icon aawp-button--icon-amazon-white\" href=\"https:\/\/www.amazon.de\/dp\/B01DZGI4I0?tag=pixolum-21&#038;linkCode=ogi&#038;th=1&#038;psc=1\" title=\"Bei Amazon ansehen\" target=\"_blank\" rel=\"nofollow noopener\">Bei Amazon ansehen<\/a>\n            <\/div>\n<\/div>\n        <\/div>\n\n    \n    <\/div>\n<\/div>\n<\/span><\/h2>\n<h2>Sicherheit f\u00fcr dich und das Pferd<\/h2>\n<p>Kommen wir nun zu einem weiteren wirklich wichtigen Punkt bei der\u00a0<strong>Pferdefotografie<\/strong>. F\u00fcr ein erfolgreiches Shooting ohne unangenehme geschweige denn gef\u00e4hrliche Zwischenf\u00e4lle ist es entscheidend, dass sich Pferd und Fotograf*in wohlf\u00fchlen.<\/p>\n<blockquote><p><strong>Ganz wichtig:<\/strong>\u00a0Als Tierfotografen verpflichten wir uns, das\u00a0<strong>Wohl<\/strong> der Tiere immer zu respektieren und zu gew\u00e4hrleisten. <strong>Kein Tier sollte leiden m\u00fcssen<\/strong>, um das\u00a0perfekte Foto zu erzeugen.<\/p><\/blockquote>\n<h3><span class=\"headingSquareNumber\">#1<\/span> Informiere dich \u00fcber Pferde<\/h3>\n<p>Die meisten Fotograf*innen, die sich mit der <strong>Pferdefotografie\u00a0<\/strong>besch\u00e4ftigen, sind von sich aus bereits Pferdefreund*innen. Doch tats\u00e4chlich kommt es auch immer wieder vor, dass sich ein*e Fotograf*in vor diesen Tieren f\u00fcrchtet und sich in ihrer Gegenwart nicht wirklich entspannen kann. Um das zu vermeiden, rate ich dir, dich im Vorfeld gut \u00fcber Pferde an sich und dein Motiv im speziellen zu informieren. Wichtig zu wissen ist beispielsweise, dass Pferde von Natur aus Beutetiere sind. Das f\u00fchrt dazu, dass das Pferd Unruhe oder \u00c4ngstlichkeit von deiner Seite stark wahrnimmt und spiegelt. Dieser biologisch bedingte Mechanismus erm\u00f6glicht es Beutetieren in freier Wildbahn, sich gegenseitig zu warnen, wenn ein Raubtier in der N\u00e4he ist. Versuche also, deine eventuelle Nervosit\u00e4t nicht nach au\u00dfen wirken zu lassen. Nat\u00fcrlich reagiert das Pferd ebenfalls \u00e4ngstlich, wenn du bedrohlich oder aggressiv auf es einwirkst. <strong>Das solltest du unter allen Umst\u00e4nden vermeiden.<\/strong><\/p>\n<h3><span class=\"headingSquareNumber\">#2<\/span> Sei dir der Risiken bewusst<\/h3>\n<p>Ja, Pferde sind Beutetiere und ihr Hauptinstinkt ist die Flucht. Sie reagieren oft schreckhaft auf Ger\u00e4usche oder pl\u00f6tzliche Bewegungen (bedenke dabei auch deine Kamera). Trotzdem solltest du dir bewusst sein, dass sie durchaus gef\u00e4hrlich werden k\u00f6nnen. Ein Pferd kann dich attackieren &#8211; z.B. bei\u00dfen oder treten. Es kann dir in seiner Panik aber auch ohne b\u00f6se Absicht &#8211; allein durch seine Gr\u00f6\u00dfe und sein Gewicht &#8211; gro\u00dfen Schaden zuf\u00fcgen.<\/p>\n<blockquote><p>Die allgemein bekannte Regel\u00a0<strong>sich einem\u00a0Pferd nie von hinten zu n\u00e4hern\u00a0<\/strong>kommt nicht von ungef\u00e4hr:\u00a0<strong>VORSICHT\u00a0<\/strong>ist hier angebracht.<\/p><\/blockquote>\n<figure id=\"attachment_5978\" aria-describedby=\"caption-attachment-5978\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5978\" style=\"margin-bottom: -1ex\" src=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-sicherheit-800x1202.jpg\" alt=\"Pferdefotografie - Pferd im Gehege\" width=\"800\" height=\"1202\" title=\"\" srcset=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-sicherheit-800x1202.jpg 800w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-sicherheit-250x376.jpg 250w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-sicherheit-120x180.jpg 120w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-5978\" class=\"wp-caption-text\">Stelle die Sicherheit aller Teilnehmer am Set sicher (@Pixabay, pexels)<\/figcaption><\/figure>\n<h3><span class=\"headingSquareNumber\">#3<\/span> Mach dich vorher mit &#8222;deinem&#8220; Pferd vertraut<\/h3>\n<p>Genau wie wir Menschen haben auch Pferde ganz unterschiedliche Pers\u00f6nlichkeiten und ihre Reaktionen auf verschiedene Situationen lassen sich nicht pauschal absch\u00e4tzen. Deine\u00a0<a href=\"https:\/\/www.bfu.ch\/de\/ratgeber\/reiten\" target=\"_blank\" rel=\"noopener\">Sicherheit<\/a>\u00a0und die &#8222;deines&#8220; Pferdes stehen im direkten Zusammenhang und sind nicht zuletzt abh\u00e4ngig von eurem pers\u00f6nlichen Verh\u00e4ltnis. Dabei kann dir &#8211; neben wichtigen allgemeinen Informationen \u00fcber Pferde &#8211; auch der Halter des Tieres behilflich sein. Ich rate dir, bereits vor dem Shooting so viel Zeit wie m\u00f6glich mit dem Pferd zu verbringen, sodass ihr euch ohne das Drumherum von Kamera, Setting und sonstigen Stressfaktoren kennenlernen und ann\u00e4hern k\u00f6nnt.<\/p>\n<div class=\"tippbox\">\n<h5>Be the boss!<\/h5>\n<p>Es gibt auch Pferde, die Nervosit\u00e4t und \u00c4ngstlichkeit des Menschen nicht unbedingt spiegeln, sondern beginnen, diese Unsicherheit auszunutzen. Es ist also auch wichtig, deine Souver\u00e4nit\u00e4t zu zeigen, damit sich dein tierischer Partner nicht ermuntert f\u00fchlt, dir auf der Nase herumzutanzen.<\/p>\n<\/div>\n<h4>Spezialtipp<\/h4>\n<p>Einen ganz konkreter Tipp f\u00fcr die ideale Vorbereitung des Shootings m\u00f6chte ich dir noch ans Herz legen. Nimm dir vor Beginn der Aufnahmen etwas Zeit, um das Pferd mit deiner Ausr\u00fcstung vertraut zu machen. Wie bereits mehrfach erw\u00e4hnt sind Pferde eher schreckhafte Tiere und k\u00f6nnen gerade auf mechanische Ger\u00e4usche wie beispielsweise den Ausl\u00f6ser einer Kamera panisch reagieren. Lass dich also am besten zun\u00e4chst etwas beschnuppern, sprich mit dem Tier und gib ihm &#8211; sofern der oder die Pferdef\u00fchrer*in einverstanden ist &#8211; ein paar <a href=\"https:\/\/amzn.to\/2NnVNGD\" target=\"_blank\" rel=\"noopener\">Leckerlis<\/a>. Wenn du das Gef\u00fchl hast, dass das Pferd ruhig und ausgeglichen ist, kannst du zum Test ein paar Ausl\u00f6serger\u00e4usche machen und seine Reaktion beobachten. Wirkt es dann tats\u00e4chlich verschreckt, empfehle ich dir zu einem Teleobjektiv zu greifen und den Abstand zu deinem Motiv so etwas zu vergr\u00f6\u00dfern.<\/p>\n<figure id=\"attachment_5984\" aria-describedby=\"caption-attachment-5984\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5984 size-large\" src=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-hintergrund-800x530.jpg\" alt=\"Pferd vorbereiten auf Shooting\" width=\"800\" height=\"530\" title=\"\" srcset=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-hintergrund-800x530.jpg 800w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-hintergrund-250x166.jpg 250w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-hintergrund-120x79.jpg 120w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-5984\" class=\"wp-caption-text\">Lass dich beschnuppern und mache Ausl\u00f6seger\u00e4usche (@alecuffia, unsplash)<\/figcaption><\/figure>\n<h3><span class=\"headingSquareNumber\">#4<\/span> Respektiere Grenzen<\/h3>\n<p>Zum Verh\u00e4ltnis von Mensch und Pferd geh\u00f6rt auch das Bewusstsein f\u00fcr die Grenzen des Anderen. Nat\u00fcrlich solltest du dich in deiner Intimsph\u00e4re sicher und wohl f\u00fchlen, dasselbe gilt allerdings auch f\u00fcr das Pferd. Frage den oder die Pferdef\u00fchrer*in, wo die physischen und psychischen Grenzen des Tieres liegen, ob und wo es ber\u00fchrt oder gestreichelt werden m\u00f6chte, welches Futter es besonders mag, wovor es spezielle Angst hat etc. Nur wenn sich Mensch und Tier entspannen k\u00f6nnen, erh\u00e4ltst du ein wunschgem\u00e4\u00dfes Ergebnis deines Shootings. Noch mehr Infos \u00fcber Tierfotografie findest du <a href=\"https:\/\/www.pixolum.com\/blog\/fotografie\/tierfotografie\">hier<\/a>.<\/p>\n<blockquote><p>Kein noch so tolles Bild rechtfertigt einen \u00dcbertritt von Grenzen oder eine psychische oder physische Verletzung von Mensch oder Tier!<\/p><\/blockquote>\n<h3><span class=\"headingSquareNumber\">#5<\/span> H\u00f6re auf den Pferdef\u00fchrer<\/h3>\n<p>Dieser Punkt ist das h\u00f6chste Gebot der Sicherheitsvorkehrungen f\u00fcr alle Beteiligten der <strong>Pferdefotografie<\/strong>. Egal wie viel du \u00fcber Pferde wei\u00dft, egal wie gut du &#8222;dein&#8220; Pferd bereits zu kennen und einsch\u00e4tzen zu k\u00f6nnen glaubst, das Wort des Pferdef\u00fchrers oder der Pferdef\u00fchrerin gilt immer als letzte Instanz. Er oder sie kann auch kleinste Anzeichen von Stress oder Unwillen des Pferdes interpretieren und vermag die Situation deshalb IMMER am besten einzusch\u00e4tzen.<\/p>\n<div class=\"tippbox\">\n<h5>WICHTIG<\/h5>\n<p>Was auch immer du tust, stelle dich NIE gegen die Anweisungen des Pferdef\u00fchrers oder der Pferdef\u00fchrerin. Sie kennen ihr Pferd am besten und haben deshalb die h\u00f6chste Entscheidungsautorit\u00e4t.<\/p>\n<\/div>\n<h2>Bildkomposition<\/h2>\n<p>Wie in anderen <a href=\"https:\/\/www.pixolum.com\/blog\/fotografie\/21-bereiche-der-fotografie-welcher-ist-der-richtige-fuer-mich\">fotografischen Disziplinen\u00a0<\/a>ist auch bei der Pferdefotografie die Bildkomposition das A und O. Da es sich um ein belebtes und unter Umst\u00e4nden auch bewegtes Motiv handelt, sind einige Faktoren besonders zu beachten. Auch ist dein Motiv nur bedingt zu kontrollieren, sodass du deine Idee von der Bildkomposition oft spontan und sehr schnell \u00fcberdenken muss. Mit diesen Tipps gelingt es dir garantiert.<\/p>\n<h3><span class=\"headingSquareNumber\">#1<\/span>\u00a0Nutze den Negativen Raum<\/h3>\n<p>Ein gro\u00dfer Teil der Faszination, die von Pferden ausgeht, ist ihre kraftvolle und elegante Beweglichkeit. Auch wenn ein Foto nur den Bruchteil eines Bewegungsablaufs einfriert, l\u00e4sst sich dieser vom Betrachter oft weiterdenken. Um das zu unterst\u00fctzen, machst du dir am besten den &#8222;negativen Raum&#8220; zunutze. <a href=\"https:\/\/www.pixolum.com\/blog\/fotografie\/positiver-negativer-raum\">Hier<\/a> kannst du noch einmal nachlesen, was das genau ist. Am besten l\u00e4sst du in der Bewegungsrichtung des Pferdes einen gr\u00f6\u00dferen Bereich offen, sodass der Eindruck entsteht, das Motiv durchquere den Bildausschnitt. Ist der Weg des Pferdes durch den Bildrand oder \u00a0weitere Elemente abgeschnitten, wirkt es in seiner Bewegungsfreiheit eingeschr\u00e4nkt und das Foto verliert seinen Zauber.<\/p>\n<figure id=\"attachment_5883\" aria-describedby=\"caption-attachment-5883\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5883 size-large\" src=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-titelbild-800x533.jpg\" alt=\"Pferdefotografie Negativer Raum\" width=\"800\" height=\"533\" title=\"\" srcset=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-titelbild-800x533.jpg 800w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-titelbild-250x167.jpg 250w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-titelbild-120x80.jpg 120w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-5883\" class=\"wp-caption-text\">Negativen Raum lassen. \u00fcberf\u00fclle das Bild nicht. (@Helena Lopes, pexels)<\/figcaption><\/figure>\n<h3><span class=\"headingSquareNumber\">#2<\/span>\u00a0Detailbilder<\/h3>\n<p>Nat\u00fcrlich stimmt es, dass Pferde gerade durch ihre Gr\u00f6\u00dfe und Bewegungen imposant wirken. Doch gerade weil die meisten Menschen Pferde nur von Ferne zu Gesicht bekommen, k\u00f6nnen Detailfotos und Nahaufnahmen eine sehr reizvolle Alternative bilden. Ein <a href=\"https:\/\/www.pixolum.com\/blog\/portraitfotografie\">Portr\u00e4t<\/a> des Pferdekopfes, oder sogar noch kleinere Elemente wie ein Auge, ein Ohr oder ein Detail des Zaumzeugs wirken genau so einzigartig und interessant wie ein Ganzk\u00f6rperbild, w\u00e4hrend sie eine spezielle Atmosph\u00e4re der Intimit\u00e4t erzeugen. Du bringst dem Betrachter damit ein Bild nahe, das sich ihm im wahren Leben vermutlich nie geboten h\u00e4tte und triffst damit genau den Kern der Pferdefotografie.<\/p>\n<figure id=\"attachment_5982\" aria-describedby=\"caption-attachment-5982\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5982 size-large\" src=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-detailaufnahme-auge-800x534.jpg\" alt=\"Pferdefotografie Detailaufnahme Auge\" width=\"800\" height=\"534\" title=\"\" srcset=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-detailaufnahme-auge-800x534.jpg 800w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-detailaufnahme-auge-250x167.jpg 250w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-detailaufnahme-auge-120x80.jpg 120w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-5982\" class=\"wp-caption-text\">Detailaufnahmen vom Auge eines Pferdes (@jeztimms, unsplash)<\/figcaption><\/figure>\n<h3><span class=\"headingSquareNumber\">#3<\/span>\u00a0Hintergrund<\/h3>\n<p>Dieser wichtige Punkt gilt nicht nur f\u00fcr die Pferdefotografie, sondern f\u00fcr alle fotografischen Disziplinen: Der Hintergrund spielt f\u00fcr die Qualit\u00e4t deines Fotos eine entscheidende Rolle. Sind die Farben und Strukturen der Umgebung denen deines Motivs zu \u00e4hnlich, wirkt das Bild flach und wenig interessant. Erst durch den Kontrast zwischen Vordergrund, Motiv und Hintergrund erwacht die Bildkomposition zum Leben und zieht das Auge des Betrachters an.<\/p>\n<p>Nat\u00fcrlich kannst du als Fotograf*in nur bedingt Einfluss auf die Umgebung nehmen und bist dabei oft den Umst\u00e4nden ausgeliefert. Das gilt vor allem f\u00fcr die Pferdefotografie, da ein Transport des Motivs an einen geeigneten Ort eventuell nicht durchf\u00fchrbar ist. Das Wohl des Tieres steht hier wie immer an h\u00f6chster Stelle, au\u00dferdem besitzt nicht jede*r Pferdehalter*in einen Transportanh\u00e4nger. Deshalb sind hier deine Anpassungsf\u00e4higkeit und Kreativit\u00e4t gefragt, um das Beste aus der Situation herauszuholen.<\/p>\n<figure id=\"attachment_6036\" aria-describedby=\"caption-attachment-6036\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6036 size-large\" src=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/Pferdefotografie-Unscharfer-Hintergrund-800x533.jpg\" alt=\"Pferdefotografie Unscharfer Hintergrund\" width=\"800\" height=\"533\" title=\"\" srcset=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/Pferdefotografie-Unscharfer-Hintergrund-800x533.jpg 800w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/Pferdefotografie-Unscharfer-Hintergrund-250x166.jpg 250w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/Pferdefotografie-Unscharfer-Hintergrund-120x80.jpg 120w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/Pferdefotografie-Unscharfer-Hintergrund.jpg 1200w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-6036\" class=\"wp-caption-text\">Hebe das Motiv vom Hintergrund ab.<\/figcaption><\/figure>\n<h4>Tipps f\u00fcr einen geeigneten Hintergrund<\/h4>\n<ul class=\"iconlist\">\n<li>Mache dir zun\u00e4chst bewusst, welches die f\u00fcr dich unver\u00e4nderbaren Parameter der Umgebung sind (R\u00e4umlichkeiten bzw. Landschaft, Licht etc.)<\/li>\n<li>Versuche nun, diese Gegebenheiten kreativ einzubinden und experimentiere mit variablen Details. \u00dcbe dich dabei in Geduld und Kompromissbereitschaft.<\/li>\n<li>Wenn du deine grobe Bildkomposition gefunden hast, nutze die Einstellungen deiner Kamera f\u00fcr ein optimales Ergebnis.<\/li>\n<li>Versuche zum Beispiel, mithilfe einer weit ge\u00f6ffneten <a href=\"https:\/\/www.pixolum.com\/blog\/fotografie\/blende\">Blende<\/a> den Hintergrund unscharf und verwaschen zu gestalten. Hier findest du eine ausf\u00fchrliche Erkl\u00e4rung der <a href=\"https:\/\/www.pixolum.com\/blog\/fotografie\/tiefenschaerfe\">Tiefensch\u00e4rfe<\/a> mit Tipps zu ihrer optimalen Verwendung.<\/li>\n<li>Auch in der Nachbearbeitung kannst du kleine Unebenheiten in deiner Bildkomposition und der Gestaltung des Hintergrundes noch ausgleichen und optimieren.<\/li>\n<\/ul>\n<div class=\"tippbox\">\n<h5>Beispiel<\/h5>\n<p>Nimm als Szene ein dunkelbraunes Pferd in einem schattigen Stall. Da die Farben von Motiv und Hintergrund sich kaum voneinander abheben, rate ich dir zu einer \u00dcberbelichtung von ein bis zwei Blendenstufen bei der Aufnahme. In der Nachbearbeitung kannst du den Farbreichtum dann ganz bequem anpassen und erh\u00e4ltst so einen optimalen Kontrast und damit ein interessantes und ansprechendes Bild.<\/p>\n<\/div>\n<h3><span class=\"headingSquareNumber\">#4<\/span> Was f\u00fcr ein Pferd fotografierst du?<\/h3>\n<p>Bei der Konzeption deiner Bildkomposition solltest du nicht zuletzt das individuelle Auftreten deines Motivs im Kopf haben. Es gibt die verschiedensten\u00a0<a href=\"https:\/\/www.tierchenwelt.de\/haustiere\/pferde\/3086-pferderassen-charakter.html\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Pferderassen<\/a>, die sich unter anderem in Bezug auf Aussehen, Haltung und Wirkung stark unterscheiden. Eventuell hast du noch gar kein spezifisches Pferd an der Hand &#8211; dann empfiehlt sich eine Internetrecherche zu den unterschiedlichen Rassen. Nicht nur die \u00e4u\u00dferen Merkmale, sondern auch die ganz besondere Ausstrahlung &#8222;deines&#8220; Pferdes beeinflussen die Bildkomposition!<\/p>\n<h2>Einstellungen<\/h2>\n<p>\u00dcber die ideale Ausr\u00fcstung f\u00fcr die Pferdefotografie haben wir bereits gesprochen. Doch wie du dir bereits denken kannst: Sie sollte auch optimal angewendet werden! Meine pers\u00f6nlichen Tipps bez\u00fcglich der Kameraeinstellungen bei der Pferdefotografie verrate ich dir in den folgenden Kapiteln.<\/p>\n<h3><span class=\"headingSquareNumber\">#1<\/span>\u00a0Fotografiere im Serienbild-Modus (Burst-Mode)<\/h3>\n<p>Wenn du schon einmal mit Tieren gearbeitet hast, wirst du es kennen: Sie interessieren sich relativ wenig daf\u00fcr, ob du ein gutes Foto hinbekommst und ob du dir daf\u00fcr w\u00fcnschst, dass sie stillhalten. Auch in der Pferdefotografie wird dir das ziemlich sicher passieren. Das Pferd blinzelt, dreht den Kopf, bewegt die Ohren oder schnappt nach einer Fliege &#8211; und deine Bildkomposition ist im Eimer. Doch keine Sorge, f\u00fcr solche Situationen eignet sich der Serienbildmodus deiner Kamera perfekt. Damit nimmst du einfach einige Bilder nacheinander auf, indem du den Ausl\u00f6ser gedr\u00fcckt h\u00e4ltst. Wenn du die\u00a0<a href=\"https:\/\/www.pixolum.com\/blog\/fotografie\/8-kamera-perspektiven-fuer-die-optimale-bildwirkung\">richtige Perspektive<\/a>\u00a0erwischt hast, ist sicher ein gutes Exemplar dabei!<\/p>\n<div class=\"tippbox\" style=\"width: 800px\">\n<h5>Perspektiv-Trick<\/h5>\n<p>Achte darauf, das Pferd m\u00f6glichst aus Augenh\u00f6he zu fotografieren. So vermeidest du, dass es verzerrt bzw. \u00fcbergro\u00df dargestellt wird. Das passiert vor allem beim Fotografieren von unten.<\/p><\/div>\n<h3><span class=\"headingSquareNumber\">#2<\/span>\u00a0Servo-Autofokus<\/h3>\n<p>Neben dem unbedingt erforderlichen Burst-Modus spielt auch der\u00a0<a href=\"https:\/\/www.pixolum.com\/blog\/fotografie\/autofokuspunkte-verstehen-anleitung-fuer-fotografie-anfaenger\">Autofokus<\/a>\u00a0eine wichtige Rolle bei der Pferdefotografie. Bei den meisten Spiegelreflex- und Systemkameras kannst du nicht nur den Autofokus aktivieren, sondern hast auch noch die Wahl zwischen\u00a0<a href=\"https:\/\/www.tolga-tanik.de\/fotografie-grundlagen-autofokus-betriebsarten-one-shot-ai-servo-ai-focus\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">verschiedene Betriebs-Modi<\/a>. Einer davon, den ich dir besonders ans Herz legen m\u00f6chte, ist der Servo-Autofokus. Je nach Hersteller wird er durch unterschiedliche K\u00fcrzel dargestellt: bei Canon hei\u00dft er beispielsweise &#8222;AI Servo&#8220;, bei Nikon hingegen &#8222;AF-C&#8220;. Diese Einstellung erm\u00f6glicht es deiner Kamera, mit dem Fokus auch einem stark bewegten Motiv zu folgen. Somit erh\u00e4ltst du ein klares, scharfes Bild.<\/p>\n<p>Du suchst noch nach einer passenden Systemkamera? Dann schau doch mal in unser <a href=\"https:\/\/www.pixolum.com\/blog\/fotografie\/beste-systemkamera\">Ranking<\/a> rein!<\/p>\n<figure id=\"attachment_5981\" aria-describedby=\"caption-attachment-5981\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5981 size-large\" src=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-negativraum-800x533.jpg\" alt=\"Pferdefotografie Autofokus\" width=\"800\" height=\"533\" title=\"\" srcset=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-negativraum-800x533.jpg 800w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-negativraum-250x167.jpg 250w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-negativraum-120x80.jpg 120w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-5981\" class=\"wp-caption-text\">Pferdefotografie: Nutze den Servo Autofokus (@sephkeil, unsplash)<\/figcaption><\/figure>\n<h3><span class=\"headingSquareNumber\">#3<\/span> Verschlusszeit<\/h3>\n<p>Kommen wir zur dritten wichtigen Einstellung bei der Pferdefotografie: der Verschlusszeit. Diese \u00e4ndert sich je nach Situation. Wenn du mit diesem Thema noch nicht ganz vertraut bist, empfehle ich dir zun\u00e4chst <a href=\"https:\/\/www.pixolum.com\/blog\/fotografie\/verschlusszeit\">diesen Artikel<\/a>.<\/p>\n<h4>Pferderennen<\/h4>\n<h4><span style=\"color: #56585d;font-family: Inter, sans-serif;font-size: large\"><span style=\"font-weight: 400\">Steigen wir gleich mal rasant ein: Bei Pferderennen k\u00f6nnen die fantastischsten Bilder entstehen! Da sich die Pferde allerdings sehr schnell bewegen und du den Abstand von deinem Motiv schlecht im Voraus planen kannst, k\u00f6nnen sie dich\u00a0<\/span><span style=\"font-weight: normal\">auch vor gro\u00dfe Herausforderungen stellen. Mit diesen Tipps gelingt deine Aufnahme bestimmt:<\/span><\/span><\/h4>\n<ul class=\"iconlist\">\n<li>Nutze in jedem Fall den Serienbild-Modus.<\/li>\n<li>Stelle au\u00dferdem eine m\u00f6glichst kurze Verschlusszeit ein. Diese richtet sich nach den gegebenen Lichtverh\u00e4ltnissen.<\/li>\n<li>Sprich mit den Verantwortlichen, d.h. mit den Betreibern bzw. Ordnern des Pferderennens. Je nach Gr\u00f6\u00dfe des Events k\u00f6nnen sie dir eventuell einen Platz nahe der Rennstrecke organisieren.<\/li>\n<li>Achte generell, vor allem aber wenn du nah dran bist darauf, <strong>ohne Blitz<\/strong> zu fotografieren. Du wei\u00dft, Pferde sind sehr schreckhaft und k\u00f6nnen panisch reagieren, was besonders in einer solchen Situation sehr gef\u00e4hrlich werden kann.<\/li>\n<\/ul>\n<h4>Pferd in Action<\/h4>\n<p>Eine Technik, die dir nicht nur bei Pferderennen, sondern bei allen Situationen mit starker Bewegung des Pferdes hilft, ist das sogenannte <a href=\"https:\/\/de.wikipedia.org\/wiki\/Mitziehen\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Mitziehen<\/a>. Wie der Name bereits vermuten l\u00e4sst, wird dabei die Kamera parallel zum sich bewegenden Motiv mitgeschwenkt. Im Idealfall sind Kamerabewegung und Motivbewegung so perfekt synchronisiert, dass das Motiv gestochen scharf eingefroren wird. Dabei hilft auch eine extrem kurze Verschlusszeit (ca. 1\/2000 Sekunde). Du kannst dir sicher bereits denken, dass diese Technik einige \u00dcbung erfordert und sehr schwierig zu meistern ist. Selbst unser Beispielbild (siehe unten) ist nicht ganz scharf! Doch die M\u00fche lohnt sich, die Ergebnisse k\u00f6nnen wirklich fantastisch werden.<\/p>\n<p>Wenn du dich f\u00fcr dieses Feld interessierst, lies doch auch unseren Artikel zu\u00a0<a href=\"https:\/\/www.pixolum.com\/blog\/fotografie\/motion-blur-bewegungsunschaerfe\">Motion Blur<\/a>!<\/p>\n<figure id=\"attachment_6015\" aria-describedby=\"caption-attachment-6015\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6015 size-large\" src=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/Pferde-fotografieren-mitziehen-verschwommen-800x535.jpg\" alt=\"Pferde fotografieren mitziehen verschwommen\" width=\"800\" height=\"535\" title=\"\" srcset=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/Pferde-fotografieren-mitziehen-verschwommen-800x535.jpg 800w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/Pferde-fotografieren-mitziehen-verschwommen-250x167.jpg 250w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/Pferde-fotografieren-mitziehen-verschwommen-120x80.jpg 120w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/Pferde-fotografieren-mitziehen-verschwommen.jpg 1200w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-6015\" class=\"wp-caption-text\">Bewege deine Kamera parallel zum Motiv. (@Melissa Newkirk)<\/figcaption><\/figure>\n<h4>Events<\/h4>\n<p>Nat\u00fcrlich gibt es nicht nur Pferderennen, sondern auch andere Events wie zum Beispiel Springreit-Turniere. Bei diesen gelten allerdings in etwa die gleichen Regeln. Der Unterschied ist, dass du generell mit einem etwas gr\u00f6\u00dferen Abstand zum Motiv rechnen musst. Bei der Wahl deines Platzes gilt:<\/p>\n<ul class=\"iconlist\">\n<li>Sprich zun\u00e4chst mit dem Veranstalter bzw. den Ordnern des Events.<\/li>\n<li>Achte darauf, dass du freie Sicht auf das Pferd hast, der Ort aber trotzdem gesch\u00fctzt ist.<\/li>\n<li>Bewege dich w\u00e4hrend des Events nicht auf Pferd und Reiter*in zu und verwende keinen Blitz, um das Tier nicht zu erschrecken.<\/li>\n<\/ul>\n<figure id=\"attachment_5980\" aria-describedby=\"caption-attachment-5980\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5980 size-large\" src=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-hochsprung-800x618.jpg\" alt=\"Pferdefotografie Hochsprung\" width=\"800\" height=\"618\" title=\"\" srcset=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-hochsprung-800x618.jpg 800w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-hochsprung-250x193.jpg 250w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-hochsprung-120x93.jpg 120w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-5980\" class=\"wp-caption-text\">Pferde-Hochsprung (@devine_images, unsplash)<\/figcaption><\/figure>\n<div class=\"tippbox\">\n<h5>Hoch hinaus<\/h5>\n<p>Besonders eindrucksvoll bei solchen Events sind Bilder, die Pferd und Reiter mitten im Sprung abbilden (siehe oben). F\u00fcr diese Aufnahmen empfehle ich dir eine relativ kurze Verschlusszeit von ca. 1\/650-1\/800 Sekunde und den Serienbildmodus deiner Kamera. Bet\u00e4tige den Ausl\u00f6ser in dem Moment, in dem das Pferd vom Boden abhebt.<\/p>\n<\/div>\n<h2>Die sch\u00f6nsten Posen f\u00fcr die Pferdefotografie<\/h2>\n<p>\u00dcber die Grundlagen der Pferdefotografie habe ich dich bereits ausf\u00fchrlich aufgekl\u00e4rt. Kommen wir nun zu den Feinheiten! Details wie die Gestik und Mimik des Pferdes k\u00f6nnen dein Bild ma\u00dfgeblich beeinflussen und zu einem Meisterwerk werden lassen.<\/p>\n<h3><span class=\"headingSquareNumber\">#1<\/span> Teamwork<\/h3>\n<p>Beginnen wir mit einem grunds\u00e4tzlichen Punkt: Je besser die Zusammenarbeit mit dem Pferd funktioniert, desto m\u00fcheloser geht dir die Bildkomposition von der Hand. In den vorigen Kapiteln haben wir bereits besprochen, wie du dich mit dem Tier vertraut machen kannst. Zus\u00e4tzlich dazu hilft die auch der oder die Pferdef\u00fchrer*in. Er oder sie kann deine Ideen zu Position, Blickrichtung oder Bewegung des Motivs durch Richtungshinweise, Ablenkungsman\u00f6ver oder \u00e4hnliche Tricks umsetzen. Wenn du das Pferd beispielsweise im Galopp fotografieren m\u00f6chtest, hilft es, einen Zielpunkt (z.B. einen Zaun) und eine entsprechende Ausgangsposition festzusetzen. Dann kann der oder die Pferdef\u00fchrer*in das Tier durch einen Zuruf oder eine Geste zum Loslaufen motivieren.<\/p>\n<blockquote><p>Wusstest du, dass Pferde Herdentiere sind? Sie sind darauf programmiert, immer zur Gruppe zur\u00fcckkehren zu wollen. Diese Eigenschaft kannst du dir auch beim Shooting zunutze machen.<br \/>\n<cite><br \/>\n<\/cite><\/p><\/blockquote>\n<h3><span class=\"headingSquareNumber\">#2<\/span> Gespitzte Ohren<\/h3>\n<p>&#8230; sind ein Ausdruck von Wachsamkeit und Interesse. Diese K\u00f6rpersprache verleiht dem Pferd eine besondere Eleganz und sorgt f\u00fcr Dynamik im Bild. Durch einen kleinen (bitte nicht unangenehmen) Reiz wie das Rascheln einer T\u00fcte, Essen oder Ger\u00e4usche von deinem Smartphone erweckst du die Aufmerksamkeit des Pferdes &#8211; die Ohren heben sich und drehen sich leicht nach vorne.<\/p>\n<figure id=\"attachment_5985\" aria-describedby=\"caption-attachment-5985\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5985 size-large\" src=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-ohren-800x533.jpg\" alt=\"Pferdefotografie Ohren\" width=\"800\" height=\"533\" title=\"\" srcset=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-ohren-800x533.jpg 800w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-ohren-250x167.jpg 250w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-ohren-120x80.jpg 120w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-5985\" class=\"wp-caption-text\">Gehobene Ohren bei einem Pferd deuten auf Achtsamkeit (@thepoplartree, unsplash)<\/figcaption><\/figure>\n<h3><span class=\"headingSquareNumber\">#3<\/span>\u00a0K\u00f6rperspannung<\/h3>\n<p>Was f\u00e4llt dir als erstes ein, wenn ich dich nach besonderen K\u00f6rpermerkmalen eines Pferdes frage? Wahrscheinlich ihr gro\u00dfer, muskul\u00f6ser K\u00f6rperbau, der lange, elegante Hals und die schlanken, aber kr\u00e4ftigen Beine. Genau diese Vorz\u00fcge kommen auf einem Foto am besten zur Geltung, wenn das Pferd leichte Aktivit\u00e4t und K\u00f6rperspannung an den Tag legt. Besonders beweglich und elegant wirkt beispielsweise ein leicht geneigter Hals. Dazu kannst du (bzw. der oder die Pferdef\u00fchrer*in) das Tier ganz einfach bewegen, indem du ihm ein Leckerli anbietest. Versuche gezielt, die aktiven Muskelgruppen des Pferdes in Szene zu setzen. Dieser Prozess kann etwas dauern, das Endergebnis wird es aber sicherlich wert sein!<\/p>\n<div class=\"tippbox\">\n<h5>Ass im \u00c4rmel<\/h5>\n<p>Um dein Motiv spielerisch in Position bewegen zu k\u00f6nnen, empfehle ich dir, immer eine <a href=\"https:\/\/amzn.to\/2ZtIdZ3\" target=\"_blank\" rel=\"noopener\">Leckerli-Box<\/a> dabei zu haben. Liebe geht durch den Magen &#8211; und Aufmerksamkeit auch.<\/p>\n<\/div>\n<h3><span class=\"headingSquareNumber\">#4<\/span>\u00a0Das gewisse Etwas<\/h3>\n<p>Wie in der Portr\u00e4tfotografie arbeiten wir auch in der Pferdefotografie mit Lebewesen, die einen individuellen Charakter haben. Versuche, die Pers\u00f6nlichkeit und die Seele des Pferdes in deinen Bildern einzufangen und hab dabei keine Angst vor unkonventionellen Details. Meine Erfahrung besagt, dass Pferd, Pferdef\u00fchrer*in und Fotograf*in sich im Laufe eines Shootings immer mehr entspannen und so auch ungeplante, vertraute oder spielerische Interaktionen zustande kommen. Lege deine Kamera also nicht gleich weg, wenn du dein perfekt komponiertes Pferdefoto im Kasten hast.<\/p>\n<p><strong>Nimm dir Zeit f\u00fcr dieses gro\u00dfartige Tier und lass es die Aufnahme auf seine eigene Weise mitgestalten.<\/strong><\/p>\n<figure id=\"attachment_5987\" aria-describedby=\"caption-attachment-5987\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5987 size-large\" src=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-interaktion-800x534.jpg\" alt=\"Pferdefotografie Interaktion\" width=\"800\" height=\"534\" title=\"\" srcset=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-interaktion-800x534.jpg 800w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-interaktion-250x167.jpg 250w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2019\/08\/pferdefotografie-interaktion-120x80.jpg 120w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-5987\" class=\"wp-caption-text\">Sch\u00f6ne Interaktion zwischen Besitzer und Pferd (@richsavas, unsplash)<\/figcaption><\/figure>\n<h2>Fazit<\/h2>\n<p>Zum Schluss noch einmal die wichtigsten Tipps in K\u00fcrze:<\/p>\n<ul class=\"iconlist\">\n<li>Achte immer auf das Wohlergehen des Tieres. Es sollte sich nie bedroht oder gestresst f\u00fchlen.<\/li>\n<li>H\u00f6re zu deiner eigenen und der Sicherheit des Pferdes auf die Anweisungen des oder der Pferdef\u00fchrers*in.<\/li>\n<li>Ich empfehle dir grunds\u00e4tzlich ein Standard- oder Teleobjektiv.<\/li>\n<li>Verwende eine gro\u00dfe Blende f\u00fcr einen \u00e4sthetisch verschwommenen Hintergrund und spiele mit dem negativen Raum.<\/li>\n<li>W\u00e4hle eine kurze Verschlusszeit, vor allem wenn sich das Pferd stark bewegt.<\/li>\n<li>Nutze den Burst\/Serienbildmodus deiner Kamera<\/li>\n<\/ul>\n<p>Ich hoffe, ich konnte dir die wunderbare Disziplin der<strong> Pferdefotografie\u00a0<\/strong>mit diesem Artikel etwas n\u00e4herbringen! Ich finde besonders den Kontrast zwischen der Eleganz und Kraft eines Pferdes und seiner Sensibilit\u00e4t absolut faszinierend und einzigartig. Hast du Fragen oder Tipps f\u00fcr Kolleg*innen? Was sind deine Erfahrungen mit der Pferdefotografie? Lass es uns gerne in den Kommentaren wissen!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Pferdefotografie ist eine absolute\u00a0Leidenschaftsdisziplin &#8211; aus gutem Grund! Pferde sind eines der elegantesten, anmutigsten und majest\u00e4tischsten Motive, die du als Fotograf*in vor die Kamera bekommen kannst. Um diesen wunderbaren Tieren gerecht zu werden und mit deinen Bildern am Ende wirklich zufrieden zu sein, solltest du einige Faktoren ber\u00fccksichtigen. Doch keine Sorge! In diesem Artikel [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":6035,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[2],"tags":[122,127],"class_list":["post-5710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fotografie","tag-fotografie-tipps","tag-tutorials-anleitungen"],"_links":{"self":[{"href":"https:\/\/www.pixolum.com\/blog\/wp-json\/wp\/v2\/posts\/5710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pixolum.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pixolum.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pixolum.com\/blog\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pixolum.com\/blog\/wp-json\/wp\/v2\/comments?post=5710"}],"version-history":[{"count":41,"href":"https:\/\/www.pixolum.com\/blog\/wp-json\/wp\/v2\/posts\/5710\/revisions"}],"predecessor-version":[{"id":34750,"href":"https:\/\/www.pixolum.com\/blog\/wp-json\/wp\/v2\/posts\/5710\/revisions\/34750"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pixolum.com\/blog\/wp-json\/wp\/v2\/media\/6035"}],"wp:attachment":[{"href":"https:\/\/www.pixolum.com\/blog\/wp-json\/wp\/v2\/media?parent=5710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pixolum.com\/blog\/wp-json\/wp\/v2\/categories?post=5710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pixolum.com\/blog\/wp-json\/wp\/v2\/tags?post=5710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}