{"id":13854,"date":"2020-08-12T15:04:44","date_gmt":"2020-08-12T13:04:44","guid":{"rendered":"https:\/\/www.pixolum.com\/blog\/?p=13854"},"modified":"2023-05-22T07:43:16","modified_gmt":"2023-05-22T05:43:16","slug":"frauenportraits-outdoor","status":"publish","type":"post","link":"https:\/\/www.pixolum.com\/blog\/fotografie\/frauenportraits-outdoor","title":{"rendered":"7 Tipps f\u00fcr zauberhafte Outdoor Frauenportraits"},"content":{"rendered":"<p><strong>Outdoorportraits. Ein einfaches Wort, hinter dem sich eine unglaubliche Bandbreite an M\u00f6glichkeiten verbirgt. Ich m\u00f6chte dir in diesem Beitrag zeigen, wie ich dieses Thema angehe und worauf ich achte, wenn ich Outdoor meine emotionalen und vertr\u00e4umten Frauenportraits kreiere.<\/strong><\/p>\n<figure id=\"attachment_13860\" aria-describedby=\"caption-attachment-13860\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13860 size-large\" src=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/Frauenportraits-vertrauemt-800x534.jpg\" alt=\"Frauenportraits vertraeumt\" width=\"800\" height=\"534\" title=\"\" srcset=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/Frauenportraits-vertrauemt-800x534.jpg 800w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/Frauenportraits-vertrauemt-250x167.jpg 250w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/Frauenportraits-vertrauemt-768x513.jpg 768w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/Frauenportraits-vertrauemt-1536x1025.jpg 1536w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/Frauenportraits-vertrauemt-2048x1367.jpg 2048w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/Frauenportraits-vertrauemt-120x80.jpg 120w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-13860\" class=\"wp-caption-text\">Model: Julia (@Theresa Sujata Senti \/ Sujata Photography)<\/figcaption><\/figure>\n<blockquote><p>Dieses Bild ist an einer meiner liebsten Locations f\u00fcr Fr\u00fchlingsbilder entstanden. Leider halten sich die Kirschbl\u00fcten nur ein paar wenige Tage. Das helle Rosa l\u00e4sst die blauen Augen des Models so richtig sch\u00f6n leuchten!<br \/>\n<cite>Theresa Sujata Senti <\/cite><\/p><\/blockquote>\n<p>Ich selbst habe durch die Outdoorportraits mit der Peoplefotografie angefangen und ich liebe diese \u00abeinfache\u00bb Art von Portraits noch bis heute. Das \u00abeinfach\u00bb steht bewusst in Anf\u00fchrungszeichen, denn es gibt doch Einiges, worauf du achten kannst, damit das Foto so gelingt, wie du es dir vorstellst. Location, Outfit, Farben\u2026 Das sind nur drei der vielen Faktoren, die du bei deinem Bild nicht dem Zufall \u00fcberlassen solltest. Damit dir auch als Anf\u00e4nger tolle <strong>Frauenportraits<\/strong> gelingen, habe ich dir die f\u00fcr mich wichtigsten Tipps und Regeln zusammengestellt.<\/p>\n<h2><span class=\"headingSquareNumber\">#1<\/span> Blickwinkel und Bildwirkung<\/h2>\n<div class=\"pixol-adsense-mitte-beginn-artiel\" style=\"float: right;\" id=\"pixol-3124207333\"><script async type=\"text\/javascript\" src=\"\/\/cdn.carbonads.com\/carbon.js?serve=CE7IL2JM&placement=wwwpixolumcom\" id=\"_carbonads_js\"><\/script><\/div><p>Dein Blickwinkel beeinflusst stark, wie die <strong>Frauenportraits<\/strong> schlussendlich wirken. Wenn das Bild sanfte Sch\u00f6nheit, Vertr\u00e4umtheit, Sinnlichkeit oder auch Verletzlichkeit ausstrahlen soll, solltest du als Fotograf das Model von oben fotografieren. Sie sitzt und du stehst. Soll das Foto stolz, stark und majest\u00e4tisch wirken, hilft es, wenn du dein Model leicht von unten fotografierst (bitte nicht von zu weit unten, wir wollen ja nicht den Inhalt ihrer Nase analysieren \ud83d\ude09). Ich habe oft einen Zweitritt im Auto, den ich entweder nutzen kann, um mich oder das Model daraufzustellen. Das erlaubt einen Perspektivenwechsel, ohne das einer am Schluss Muskelkater hat. Nat\u00fcrlich kannst du dein Model auch auf Augenh\u00f6he fotografieren. Dies ist so zu sagen der neutrale Mittelweg, der die <a href=\"https:\/\/www.pixolum.com\/blog\/fotografie\/bildwirkung-optimieren-tipps-bildstil\">Bildwirkung<\/a> am wenigsten beeinflusst.<\/p>\n<blockquote><p>Die roten Hare wurden hier mutig mit den violetten Beeren eines Liebesperlenstrauchs kombiniert. Ich war anfangs nicht sicher, ob sich die Farben vertragen aber das Resultat spricht f\u00fcr sich.<br \/>\n<cite>Theresa Sujata Senti <\/cite><\/p><\/blockquote>\n<figure id=\"attachment_13862\" aria-describedby=\"caption-attachment-13862\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13862 size-large\" src=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-blickwinkel-800x534.jpg\" alt=\"frau blick vertraeumt in kamera aus einem blumenfeld\" width=\"800\" height=\"534\" title=\"\" srcset=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-blickwinkel-800x534.jpg 800w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-blickwinkel-250x167.jpg 250w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-blickwinkel-768x513.jpg 768w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-blickwinkel-1536x1026.jpg 1536w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-blickwinkel-2048x1367.jpg 2048w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-blickwinkel-120x80.jpg 120w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-13862\" class=\"wp-caption-text\">Model: Svenja Lugano Moreno \/ Make-up und Haare: Mona Schl\u00fcsing (@Theresa Sujata Senti \/ Sujata Photography)<\/figcaption><\/figure>\n<h2><span class=\"headingSquareNumber\">#2<\/span> Der Einsatz von Farben<\/h2>\n<p>Versuche bunte Bilder zu vermeiden, es sei denn, das ist gerade das Thema des Shootings. Das gilt f\u00fcr das Model, das Make-up, die Kleider und den Hintergrund. Ziehe neutrale Farben wie schwarz, weiss, grau, braun und beige vor und arbeite Ton in Ton oder setze bewusst einzelne Farbakzente. Ich empfehle dir nie mehr als zwei dominante Farben im Bild zu haben. Oft ist eine davon schon vom Model vorgegeben, zum Beispiel \u00fcber die Haarfarbe, die Augenfarbe oder falls das Model bunte Tattoos hat. Entweder bel\u00e4sst du es bei der einen dominanten Farbe und arbeitest mit ihr oder du nimmst eine zweite Farbe dazu. Diese darf (ann\u00e4hernd) komplement\u00e4r zu der ersten dominanten Farbe sein. Ein Beispiel daf\u00fcr w\u00e4ren blaue Augen und oranges Augen Make-up, rote Haare und gr\u00fcne Bl\u00e4tter oder ein gelbes Kleid gegen einen blauen Himmel.<\/p>\n<blockquote><p>Die Bl\u00e4tter im Hintergrund sind nur etwa 3 Wochen im Jahr so sch\u00f6n rot. Die Farbe des Outftis wurde entsprechend ausgesucht, die Spitze gibt dem Bild noch etwas mehr Leichtigkeit.<br \/>\n<cite>Theresa Sujata Senti <\/cite><\/p><\/blockquote>\n<figure id=\"attachment_13863\" aria-describedby=\"caption-attachment-13863\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13863 size-large\" src=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-farben-800x534.jpg\" alt=\"frauenportraits mit roter farbe im hintergrund und auf dem kleid des models\" width=\"800\" height=\"534\" title=\"\" srcset=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-farben-800x534.jpg 800w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-farben-250x167.jpg 250w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-farben-768x513.jpg 768w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-farben-1536x1026.jpg 1536w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-farben-2048x1367.jpg 2048w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-farben-120x80.jpg 120w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-13863\" class=\"wp-caption-text\">Model: Tanja M\u00fcller (@Theresa Sujata Senti \/ Sujata Photography)<\/figcaption><\/figure>\n<h2><span class=\"headingSquareNumber\">#3<\/span> Die Location und der passende Hintergrund<\/h2>\n<p>Nachdem du nun entschieden hast, wie dein Blickwinkel gegen\u00fcber dem Model sein soll und welche Farben zu deinen <strong>Frauenportraits<\/strong> passen, musst du dir als n\u00e4chstes Gedanken um den Hintergrund machen. Das kann alles M\u00f6gliche sein, vom Graffiti an einer Unterf\u00fchrung (Vorsicht wegen der Farben!), \u00fcber einen Wald, bis zur neutralen weissen Hauswand. Gerade bei vertr\u00e4umten <strong>Frauenportraits<\/strong> braucht es eigentlich nicht viel &#8211; der kleine Rosenstrauch der Nachbarn ist oft schon mehr als ausreichend. Halte daher die Augen offen, wenn du zu Fuss, mit dem Rad oder dem Auto unterwegs bist. Gerade \u00f6ffentliche Parks oder der Aussenbereich eines Firmengel\u00e4ndes k\u00f6nnen tolle M\u00f6glichkeiten bieten. Sei dir auch bewusst, dass viele <a href=\"https:\/\/www.pixolum.com\/blog\/fotografie\/lost-places\">Locations<\/a> nur ein paar Tage oder wenige Wochen im Jahr wundersch\u00f6n aussehen, den Rest der Zeit sind sie sehr unscheinbar. Es lohnt sich also immer, mit einem wachen Blick unterwegs zu sein.<\/p><div class=\"pixol-inhalt_3\" style=\"margin-bottom: 30px;\" id=\"pixol-514007833\"><h4>Kennst du schon meine 52 weltbesten Spickzettel?<\/h4>\r\n<div class=\"spickteaser\">\r\n<div class=\"row\">\r\n<div class=\"col-sm-7\">\r\n\t<a href=\"https:\/\/www.pixolum.com\/blog\/downloads\/fotografie-spickzettel?utm_source=pixolum&utm_medium=blog_inarticle&utm_campaign=spk_pix_sale_30&utm_term=p79\"><img class=\"alignnone size-full wp-image-8300\" src=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/10\/Fotospickzettel-pixolum-500px.jpg\" alt=\"Fotografie Spickzettel\" loading=\u201dlazy\u201d \/><\/a>\r\n\t<\/div>\r\n<div class=\"col-sm-5\">\r\n<a href=\"https:\/\/www.pixolum.com\/blog\/downloads\/fotografie-spickzettel?utm_source=pixolum&utm_medium=blog_inarticle&utm_campaign=spk_pix_sale_30&utm_term=p79\">\r\n\t<ul class=\"check_icon_list check_icon_list--spickzettel\">\r\n\t\t<li>Mein ganzes Fotowissen<\/li>\r\n\t\t<li>Bessere Fotos in 5 Minuten<\/li>\r\n\t\t<li>Referenz zum Nachschlagen<\/li>\r\n\t\t<li>Kompakt, immer dabei!<\/li>\r\n\t\t<li>Rabatt nicht verpassen!<b><span>-50%<\/span><\/b><\/li>\r\n\t<\/ul>\r\n\t<div class=\"trenner_30\"><\/div>\r\n<\/a>\r\n<a href=\"https:\/\/www.pixolum.com\/blog\/downloads\/fotografie-spickzettel?utm_source=pixolum&utm_medium=blog_inarticle&utm_campaign=spk_pix_sale_30&utm_term=p79\" class=\"btn btn-primary btn-lg btn-block\">Ou ja, zeig mal!<\/a><\/div>\r\n<\/div>\r\n<\/div>\r\n<hr><\/div>\n<p>Ich empfehle dir einen eher dunklen Hintergrund zu w\u00e4hlen. Das Gesicht deines Models sollte das Hellste im Bild sein, denn unser Blick wird automatisch von hellen Bereichen angezogen. Auch sonst sollten im Hintergrund keine Elemente sein, die vom Model ablenken. Wenn Elemente wie zum Beispiel Blumen im Hintergrund zu sehen sind, sollten sie eine Erg\u00e4nzung zum Model sein.<\/p>\n<h2><span class=\"headingSquareNumber\">#4<\/span> Strukturen und Muster<\/h2>\n<p>Strukturen und Muster machen das Bild spannend. Sei es ein strukturierter Hintergrund, oder, wie ich es auch gerne mache, Struktur in den Kleidern. Spitze bietet sich f\u00fcr <strong>Frauenportraits<\/strong> besonders an. Wichtig ist auch, dass die Struktur einfarbig ist und sich ins Gesamtbild einf\u00fcgt. Wenn dein Model t\u00e4towiert ist, w\u00fcrde ich empfehlen auf zus\u00e4tzliche Strukturen im Bild zu verzichten, damit der Gesamteindruck nicht zu nerv\u00f6s wirkt. Ein weiteres tolles Strukturelement sind die Haare. Wenn dein Model lange Haare hat, bitte sie, Wellen oder Locken zu machen. Das funktioniert immer, auch bei t\u00e4towierten Models und es sieht einfach spannender aus als gerade Haare.<\/p>\n<blockquote><p>Da das Model am ganzen K\u00f6rper stark t\u00e4towiert ist, wird hier alles Andere ruhig gehalten. Ein schlichter, schwarzer Hintergrund, ein unaufdringliches schwarzes Oberteil und dank der geschlossenen Augen auch eine sehr ruhige Ausstrahlung des Models.<br \/>\n<cite>Theresa Sujata Senti <\/cite><\/p><\/blockquote>\n<figure id=\"attachment_13864\" aria-describedby=\"caption-attachment-13864\" style=\"width: 683px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13864 size-large\" src=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-hintergrund-800x1199.jpg\" alt=\"frauenportraits mit schwarzem hintergrund und t\u00e4towiertem model\" width=\"683\" height=\"1024\" title=\"\" srcset=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-hintergrund-800x1199.jpg 800w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-hintergrund-250x375.jpg 250w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-hintergrund-768x1151.jpg 768w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-hintergrund-1025x1536.jpg 1025w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-hintergrund-1367x2048.jpg 1367w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-hintergrund-120x180.jpg 120w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-hintergrund-scaled.jpg 1709w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><figcaption id=\"caption-attachment-13864\" class=\"wp-caption-text\">Model: Sandy TrueBodyArt \/ Make-up und Haare: Tanja Vernucci (@Theresa Sujata Senti \/ Sujata Photography)<\/figcaption><\/figure>\n<h2><span class=\"headingSquareNumber\">#5<\/span> Blende und der Bokeh-Effekt<\/h2>\n<p>F\u00fcr meine Frauenportraits arbeite ich meist mit einer sehr offenen <a href=\"https:\/\/www.pixolum.com\/blog\/fotografie\/blende\">Blende<\/a>. So verschwimmt der Hintergrund und das Model wird nochmals st\u00e4rker betont. Je nach dem mit welchem Objektiv du arbeitest, bekommst du zudem einen wundersch\u00f6nen <a href=\"https:\/\/www.pixolum.com\/blog\/fotografie\/bokeh-effekt-tutorial-die-schoenheit-der-unschaerfe\">Bokeh-Effekt<\/a>, der das Bild f\u00fcr den Betrachter nochmals spannender macht. <a href=\"https:\/\/www.pixolum.com\/blog\/kamera-objektive\">Objektive<\/a>, die f\u00fcr ihr sch\u00f6nes und einzigartiges Bokeh bekannt sind, sind zum Beispiel das <a href=\"https:\/\/www.amazon.de\/Helios-44-2-Soviet-Panasonic-Olympus\/dp\/B00V85FLOG\" target=\"_blank\" rel=\"noopener\">Helios 44-2 58 mm f2<\/a> oder das <a href=\"https:\/\/www.amazon.de\/Meyer-Optik-G%C3%B6rlitz-Trioplan-Schraubgewinde\/dp\/B01M3PPFHZ\" target=\"_blank\" rel=\"noopener\">Trioplan 100 f2.8<\/a>.<\/p>\n<h2><span class=\"headingSquareNumber\">#6<\/span> Photoshop<\/h2>\n<p>Wenn die Realit\u00e4t nicht all deinen W\u00fcnschen entsprechen kann &#8211; dann gibt es immer noch <a href=\"https:\/\/www.pixolum.com\/blog\/fotografie\/photoshop-tipps-tastaturbefehle\">Photoshop<\/a>. Die oben genannten Eigenschaften unter einen Hut zu bekommen ist nicht immer einfach, gerade Outdoor musst du oft Kompromisse eingehen. Doch insbesondere was die Farben betrifft, kann im Post-Processing noch viel herausgeholt werden. Gr\u00fcnt\u00f6ne sind hier ein typisches Beispiel. Outdoor kommt man um diese Farbe meist nicht herum, ausser man ist in einer Stadt oder in der W\u00fcste. Sehr oft ist Gr\u00fcn dann eben diese eine Farbe zu viel. Aber das Gr\u00fcn kann auch sehr einfach in eine andere Farbe umgewandelt werden. Dazu verrate ich dir jetzt Schritt f\u00fcr Schritt meine Lieblingsmethode, welche ich bei vielen meiner Frauenportraits verwende.<\/p>\n<ol>\n<li>Lege eine Einstellungsebene \u00abKanalmixer\u00bb an<\/li>\n<li>W\u00e4hle den Ausgabekanal Blau<\/li>\n<li>Setze folgenden Werte:<br \/>\nRot: -50 %<br \/>\nGr\u00fcn: +150 %<br \/>\nBlau: 0 %<\/li>\n<li>Jetzt sollten deine Gr\u00fcnt\u00f6ne nicht mehr gr\u00fcn, sondern blau\/cyanfarben sein<\/li>\n<li>Setze den Ebenenmodus der Kanalmixer-Ebene auf \u00abAufhellen\u00bb<\/li>\n<li>Lege eine Farbton\/S\u00e4ttigungs-Ebene an, die aber nur auf die Kanalmixer-Ebene darunter angewendet wird<\/li>\n<li>W\u00e4hle nun bei Farbton\/S\u00e4ttigung die Cyant\u00f6ne aus<\/li>\n<li>Wenn du jetzt den Regler f\u00fcr den Farbton verschiebst, wirst du feststellen, dass du alle deine (ehemaligen) Gr\u00fcnt\u00f6ne nun ganz einfach umf\u00e4rben kannst<\/li>\n<li>Es bietet sich zudem an, auch mit den Reglern der S\u00e4ttigung und der Helligkeit zu spielen<\/li>\n<\/ol>\n<p>Falls du im Hintergrund noch helle Bereiche hast, die vom Model ablenken, kannst du diese entweder mit dem Stempelwerkzeug entfernen oder den Blick \u00fcber eine dunkle Vignette und gezieltes aufhellen des Gesichts lenken.<\/p>\n<blockquote><p>Bei diesem Bild wurde der gr\u00fcne Hintergrund mit der im Text beschriebenen Methode blau gef\u00e4rbt, um einen noch st\u00e4rkeren Kontrast zu den roten Haaren des Models herauszuarbeiten.<br \/>\n<cite>Theresa Sujata Senti <\/cite><\/p><\/blockquote>\n<figure id=\"attachment_13865\" aria-describedby=\"caption-attachment-13865\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13865 size-large\" src=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-photoshop-800x534.jpg\" alt=\"model blickt vertraeumt in kamera mit bokeh effekt im hintergrund\" width=\"800\" height=\"534\" title=\"\" srcset=\"https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-photoshop-800x534.jpg 800w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-photoshop-250x167.jpg 250w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-photoshop-768x513.jpg 768w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-photoshop-1536x1025.jpg 1536w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-photoshop-2048x1367.jpg 2048w, https:\/\/www.pixolum.com\/blog\/wp-content\/uploads\/2020\/08\/frauenportraits-photoshop-120x80.jpg 120w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-13865\" class=\"wp-caption-text\">Model: Leonie Wawro \/ Make-up und Haare: Jeanne-Kay Kruger (@Theresa Sujata Senti \/ Sujata Photography)<\/figcaption><\/figure>\n<h2><span class=\"headingSquareNumber\">#7<\/span> Gezielte Planung<\/h2>\n<p>Kommen wir zum Schluss noch zu dem, was eigentlich ganz am Anfang eines jeden Shootings steht &#8211; die Planung. Es kommt selten vor, dass ich ganz ohne Plan an ein Shooting gehe. Das Herangehen an die Planung kann ganz unterschiedlich sein, je nach Startpunkt. Nehmen wir mal an, dein Startpunkt ist der wundersch\u00f6ne, bl\u00fchende Magnolienbaum, den du entdeckt hast. In dem Fall solltest du dir erst die Location selber genauer anschauen.<\/p>\n<ul class=\"iconlist\">\n<li>Wie hoch oben sind die Bl\u00fcten?<\/li>\n<li>Kommen die \u00c4ste bis herunter oder brauchen sowohl du als auch das Model etwas zum Draufstehen damit du die gew\u00fcnschte Perspektive bekommst?<\/li>\n<li>Ist die Location frei zug\u00e4nglich oder musst du noch irgendwo eine Bewilligung einholen?<\/li>\n<li>Der Magnolienbaum mit seinen weiss-rosa Bl\u00fcten gibt die Farben vor. Sag deinem Model also, sie soll weisse und rosa Outfits mitnehmen und auch das Styling in den diesen T\u00f6nen halten.<\/li>\n<li>Schick dem Model am besten ein paar Fotos von der Location, damit es sich besser vorbereiten kann.<\/li>\n<li>Suche im Web, auf Instagram\/Facebook und <a href=\"https:\/\/www.pinterest.de\/\" target=\"_blank\" rel=\"noopener\">Pinterest,<\/a> Bilder von Shootings mit Magnolienb\u00e4umen und teile auch diese Bilder mit deinem Model. Zum einen liefert es weitere Inputs f\u00fcr die Outfits und dem Styling, zum anderen bringen dich die Bilder vielleicht auf Ideen, die du vielleicht selber so nicht gehabt h\u00e4ttest.<\/li>\n<li>Sammle weitere besonderen <a href=\"https:\/\/www.pixolum.com\/blog\/fotografie\/portrait-fotografieren\">Portrait-Shooting Ideen<\/a>, die dein Bild noch besonderer machen sollen<\/li>\n<\/ul>\n<p><strong>Ich hoffe, dass ich dir mit meinen Tipps ein bisschen weiterhelfen konnte und dich vielleicht auch zum einen oder anderen Experiment inspiriert habe. Wenn ja, w\u00fcrde es mich nat\u00fcrlich sehr freuen, das Resultat zu sehen! Viel Spass bei der Umsetzung und ich w\u00fcnsche dir immer gutes Licht!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Outdoorportraits. Ein einfaches Wort, hinter dem sich eine unglaubliche Bandbreite an M\u00f6glichkeiten verbirgt. Ich m\u00f6chte dir in diesem Beitrag zeigen, wie ich dieses Thema angehe und worauf ich achte, wenn ich Outdoor meine emotionalen und vertr\u00e4umten Frauenportraits kreiere. Dieses Bild ist an einer meiner liebsten Locations f\u00fcr Fr\u00fchlingsbilder entstanden. Leider halten sich die Kirschbl\u00fcten nur [&hellip;]<\/p>\n","protected":false},"author":81,"featured_media":13860,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[2],"tags":[122,125],"class_list":["post-13854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fotografie","tag-fotografie-tipps","tag-portraitfotografie"],"_links":{"self":[{"href":"https:\/\/www.pixolum.com\/blog\/wp-json\/wp\/v2\/posts\/13854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pixolum.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pixolum.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pixolum.com\/blog\/wp-json\/wp\/v2\/users\/81"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pixolum.com\/blog\/wp-json\/wp\/v2\/comments?post=13854"}],"version-history":[{"count":15,"href":"https:\/\/www.pixolum.com\/blog\/wp-json\/wp\/v2\/posts\/13854\/revisions"}],"predecessor-version":[{"id":61438,"href":"https:\/\/www.pixolum.com\/blog\/wp-json\/wp\/v2\/posts\/13854\/revisions\/61438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pixolum.com\/blog\/wp-json\/wp\/v2\/media\/13860"}],"wp:attachment":[{"href":"https:\/\/www.pixolum.com\/blog\/wp-json\/wp\/v2\/media?parent=13854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pixolum.com\/blog\/wp-json\/wp\/v2\/categories?post=13854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pixolum.com\/blog\/wp-json\/wp\/v2\/tags?post=13854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}